{"id":1489,"count":1,"description":"","link":"https:\/\/birmingham-trend.com\/en\/tag\/cinema-in-birmingham","name":"cinema in Birmingham","slug":"cinema-in-birmingham","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/birmingham-trend.com\/en\/wp-json\/wp\/v2\/tags\/1489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/birmingham-trend.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/birmingham-trend.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/birmingham-trend.com\/en\/wp-json\/wp\/v2\/posts?tags=1489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}