{"id":224,"count":1,"description":"","link":"https:\/\/birmingham-trend.com\/ru\/tag\/lourens-olive","name":"\u041b\u043e\u0443\u0440\u0435\u043d\u0441 \u041e\u043b\u0438\u0432\u044c\u0435","slug":"lourens-olive","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/birmingham-trend.com\/ru\/wp-json\/wp\/v2\/tags\/224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/birmingham-trend.com\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/birmingham-trend.com\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/birmingham-trend.com\/ru\/wp-json\/wp\/v2\/posts?tags=224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}