{"id":678,"count":1,"description":"","link":"https:\/\/birmingham-trend.com\/ru\/tag\/detskie-peredachi","name":"\u0434\u0435\u0442\u0441\u043a\u0438\u0435 \u043f\u0435\u0440\u0435\u0434\u0430\u0447\u0438","slug":"detskie-peredachi","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/birmingham-trend.com\/ru\/wp-json\/wp\/v2\/tags\/678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/birmingham-trend.com\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/birmingham-trend.com\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/birmingham-trend.com\/ru\/wp-json\/wp\/v2\/posts?tags=678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}