{"id":1394,"count":1,"description":"","link":"https:\/\/birmingham-trend.com\/uk\/tag\/progressive-rock-history","name":"progressive rock history","slug":"progressive-rock-history","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/birmingham-trend.com\/uk\/wp-json\/wp\/v2\/tags\/1394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/birmingham-trend.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/birmingham-trend.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/birmingham-trend.com\/uk\/wp-json\/wp\/v2\/posts?tags=1394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}